{"id":11522,"date":"2020-09-09T15:12:45","date_gmt":"2020-09-09T14:12:45","guid":{"rendered":"https:\/\/divertarte.com\/?post_type=product&#038;p=11522"},"modified":"2025-11-07T09:54:37","modified_gmt":"2025-11-07T09:54:37","slug":"frasco-500-ml-transparente-com-tampa-vaporizadora-pistola","status":"publish","type":"product","link":"https:\/\/divertarte.com\/index.php\/produto\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\/","title":{"rendered":"Frasco 500 ml transparente com tampa vaporizadora pistola"},"content":{"rendered":"<p>Frasco 500 ml transparente com tampa vaporizadora pistola<\/p>\n<p>Ideal para frasco de \u00e1lcool, desinfectante . Para al\u00e9m disso pode ser usado como borrifador.<\/p>\n<p>Medida do frasco \u00d87.5 x altura 19 cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frasco 500 ml transparente com tampa vaporizadora pistola<\/p>\n<p>Ideal para frasco de \u00e1lcool, desinfectante . Para al\u00e9m disso pode ser usado como borrifador.<\/p>\n<p>Medida do frasco \u00d87.5 x altura 19 cm<\/p>\n","protected":false},"featured_media":18520,"comment_status":"open","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[168],"product_tag":[738,589,462],"class_list":["post-11522","product","type-product","status-publish","has-post-thumbnail","product_cat-frascos-pet-frascos-plastico-boioes-boiao-pet","product_tag-frasco-pet","product_tag-frascos-desinfetante","product_tag-frascos-plastico","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Frasco 500 ml transparente com tampa vaporizadora pistola -<\/title>\n<meta name=\"description\" content=\"Frasco 500 ml transparente com tampa vaporizadora pistola Ideal para frasco de \u00e1lcool, desinfectante, pode ser usado como borrifador.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/divertarte.com\/index.php\/produto\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frasco 500 ml transparente com tampa vaporizadora pistola -\" \/>\n<meta property=\"og:description\" content=\"Frasco 500 ml transparente com tampa vaporizadora pistola Ideal para frasco de \u00e1lcool, desinfectante, pode ser usado como borrifador.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/divertarte.com\/index.php\/produto\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-07T09:54:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/divertarte.com\/wp-content\/uploads\/2020\/09\/Frasco-500-ml-transparente-com-tampa-vaporizadora-pistola.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"324\" \/>\n\t<meta property=\"og:image:height\" content=\"336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/divertarte.com\\\/index.php\\\/produto\\\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\\\/\",\"url\":\"https:\\\/\\\/divertarte.com\\\/index.php\\\/produto\\\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\\\/\",\"name\":\"Frasco 500 ml transparente com tampa vaporizadora pistola -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/divertarte.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/divertarte.com\\\/index.php\\\/produto\\\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/divertarte.com\\\/index.php\\\/produto\\\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/divertarte.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Frasco-500-ml-transparente-com-tampa-vaporizadora-pistola.jpg\",\"datePublished\":\"2020-09-09T14:12:45+00:00\",\"dateModified\":\"2025-11-07T09:54:37+00:00\",\"description\":\"Frasco 500 ml transparente com tampa vaporizadora pistola Ideal para frasco de \u00e1lcool, desinfectante, pode ser usado como borrifador.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/divertarte.com\\\/index.php\\\/produto\\\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/divertarte.com\\\/index.php\\\/produto\\\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/divertarte.com\\\/index.php\\\/produto\\\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/divertarte.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Frasco-500-ml-transparente-com-tampa-vaporizadora-pistola.jpg\",\"contentUrl\":\"https:\\\/\\\/divertarte.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Frasco-500-ml-transparente-com-tampa-vaporizadora-pistola.jpg\",\"width\":324,\"height\":336},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/divertarte.com\\\/index.php\\\/produto\\\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/divertarte.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/divertarte.com\\\/index.php\\\/divertarte-produtos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Frasco 500 ml transparente com tampa vaporizadora pistola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/divertarte.com\\\/#website\",\"url\":\"https:\\\/\\\/divertarte.com\\\/\",\"name\":\"Divertarte\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/divertarte.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/divertarte.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/divertarte.com\\\/#organization\",\"name\":\"Divertarte\",\"url\":\"https:\\\/\\\/divertarte.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/divertarte.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/divertarte.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-div.jpg\",\"contentUrl\":\"https:\\\/\\\/divertarte.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-div.jpg\",\"width\":295,\"height\":123,\"caption\":\"Divertarte\"},\"image\":{\"@id\":\"https:\\\/\\\/divertarte.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frasco 500 ml transparente com tampa vaporizadora pistola -","description":"Frasco 500 ml transparente com tampa vaporizadora pistola Ideal para frasco de \u00e1lcool, desinfectante, pode ser usado como borrifador.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/divertarte.com\/index.php\/produto\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\/","og_locale":"pt_PT","og_type":"article","og_title":"Frasco 500 ml transparente com tampa vaporizadora pistola -","og_description":"Frasco 500 ml transparente com tampa vaporizadora pistola Ideal para frasco de \u00e1lcool, desinfectante, pode ser usado como borrifador.","og_url":"https:\/\/divertarte.com\/index.php\/produto\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\/","article_modified_time":"2025-11-07T09:54:37+00:00","og_image":[{"width":324,"height":336,"url":"https:\/\/divertarte.com\/wp-content\/uploads\/2020\/09\/Frasco-500-ml-transparente-com-tampa-vaporizadora-pistola.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/divertarte.com\/index.php\/produto\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\/","url":"https:\/\/divertarte.com\/index.php\/produto\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\/","name":"Frasco 500 ml transparente com tampa vaporizadora pistola -","isPartOf":{"@id":"https:\/\/divertarte.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/divertarte.com\/index.php\/produto\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\/#primaryimage"},"image":{"@id":"https:\/\/divertarte.com\/index.php\/produto\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\/#primaryimage"},"thumbnailUrl":"https:\/\/divertarte.com\/wp-content\/uploads\/2020\/09\/Frasco-500-ml-transparente-com-tampa-vaporizadora-pistola.jpg","datePublished":"2020-09-09T14:12:45+00:00","dateModified":"2025-11-07T09:54:37+00:00","description":"Frasco 500 ml transparente com tampa vaporizadora pistola Ideal para frasco de \u00e1lcool, desinfectante, pode ser usado como borrifador.","breadcrumb":{"@id":"https:\/\/divertarte.com\/index.php\/produto\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/divertarte.com\/index.php\/produto\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/divertarte.com\/index.php\/produto\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\/#primaryimage","url":"https:\/\/divertarte.com\/wp-content\/uploads\/2020\/09\/Frasco-500-ml-transparente-com-tampa-vaporizadora-pistola.jpg","contentUrl":"https:\/\/divertarte.com\/wp-content\/uploads\/2020\/09\/Frasco-500-ml-transparente-com-tampa-vaporizadora-pistola.jpg","width":324,"height":336},{"@type":"BreadcrumbList","@id":"https:\/\/divertarte.com\/index.php\/produto\/frasco-500-ml-transparente-com-tampa-vaporizadora-pistola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/divertarte.com\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/divertarte.com\/index.php\/divertarte-produtos\/"},{"@type":"ListItem","position":3,"name":"Frasco 500 ml transparente com tampa vaporizadora pistola"}]},{"@type":"WebSite","@id":"https:\/\/divertarte.com\/#website","url":"https:\/\/divertarte.com\/","name":"Divertarte","description":"","publisher":{"@id":"https:\/\/divertarte.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/divertarte.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/divertarte.com\/#organization","name":"Divertarte","url":"https:\/\/divertarte.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/divertarte.com\/#\/schema\/logo\/image\/","url":"https:\/\/divertarte.com\/wp-content\/uploads\/2018\/07\/logo-div.jpg","contentUrl":"https:\/\/divertarte.com\/wp-content\/uploads\/2018\/07\/logo-div.jpg","width":295,"height":123,"caption":"Divertarte"},"image":{"@id":"https:\/\/divertarte.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/divertarte.com\/index.php\/wp-json\/wp\/v2\/product\/11522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divertarte.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divertarte.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divertarte.com\/index.php\/wp-json\/wp\/v2\/comments?post=11522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divertarte.com\/index.php\/wp-json\/wp\/v2\/media\/18520"}],"wp:attachment":[{"href":"https:\/\/divertarte.com\/index.php\/wp-json\/wp\/v2\/media?parent=11522"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divertarte.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=11522"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divertarte.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=11522"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divertarte.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=11522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}